{"id":2501,"date":"2026-07-09T13:24:05","date_gmt":"2026-07-09T16:24:05","guid":{"rendered":"https:\/\/exatas.ufpr.br\/cegraf\/?p=2501"},"modified":"2026-07-09T14:00:27","modified_gmt":"2026-07-09T17:00:27","slug":"matricula-2o-semestre-2026","status":"publish","type":"post","link":"https:\/\/exatas.ufpr.br\/cegraf\/matricula-2o-semestre-2026\/","title":{"rendered":"Matr\u00edcula 2\u00ba semestre 2026"},"content":{"rendered":"\n<p>No per\u00edodo de <strong>13 a 15 de julho<\/strong>, ocorrer\u00e1 o per\u00edodo de matr\u00edculas via SIGA. A coordena\u00e7\u00e3o do curso de Express\u00e3o Gr\u00e1fica indicar\u00e1 as disciplinas em que cada estudante DEVE se matricular em planilha enviado junto a essa orienta\u00e7\u00e3o. Lembrando que essa indica\u00e7\u00e3o leva em considera\u00e7\u00e3o o melhor fluxo de integraliza\u00e7\u00e3o, casos n\u00e3o justificados do n\u00e3o seguimento da indica\u00e7\u00e3o levar\u00e3o ao ajuste da coordena\u00e7\u00e3o ao plano indicado. Os documentos de orienta\u00e7\u00e3o para matr\u00edcula foram encaminhado via SIGA por e-mail e pelo grupo do curso no Whatsapp.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No per\u00edodo de 13 a 15 de julho, ocorrer\u00e1 o per\u00edodo de matr\u00edculas via SIGA. A coordena\u00e7\u00e3o do curso de Express\u00e3o Gr\u00e1fica indicar\u00e1 as disciplinas em que cada estudante DEVE se matricular em planilha enviado junto a essa orienta\u00e7\u00e3o. Lembrando que essa indica\u00e7\u00e3o leva em considera\u00e7\u00e3o o melhor fluxo de integraliza\u00e7\u00e3o, casos n\u00e3o justificados do [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2501","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/posts\/2501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/comments?post=2501"}],"version-history":[{"count":3,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/posts\/2501\/revisions"}],"predecessor-version":[{"id":2512,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/posts\/2501\/revisions\/2512"}],"wp:attachment":[{"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/media?parent=2501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/categories?post=2501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exatas.ufpr.br\/cegraf\/wp-json\/wp\/v2\/tags?post=2501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}